{"id":4204,"date":"2023-12-21T15:30:00","date_gmt":"2023-12-21T15:30:00","guid":{"rendered":"https:\/\/steelblue-quail-777252.hostingersite.com\/?page_id=4204"},"modified":"2025-05-22T09:06:49","modified_gmt":"2025-05-22T09:06:49","slug":"riservatezza","status":"publish","type":"page","link":"https:\/\/hurento.ma\/it\/riservatezza\/","title":{"rendered":"Riservatezza"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4204\" class=\"elementor elementor-4204 elementor-761\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55ae1c1 e-flex e-con-boxed e-con e-parent\" data-id=\"55ae1c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01eed39 elementor-widget elementor-widget-text-editor\" data-id=\"01eed39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Hurento.ma Informativa sulla privacy<\/h1><h2>1. Introduzione<\/h2><p>Benvenuti a Hurento. La presente Informativa sulla privacy spiega come noi di Hurento raccogliamo, utilizziamo, divulghiamo e proteggiamo le informazioni personali degli utenti del nostro sito. <\/p><h2>2. Raccolta di informazioni<\/h2><p>Raccogliamo informazioni quando navighi sul nostro sito, ti registri sul nostro sito e utilizzi i nostri servizi. I tipi di informazioni raccolte possono includere il nome, l \u201cindirizzo e-mail, il numero di telefono e l\u201d indirizzo IP. <\/p><h2>3. Utilizzo delle informazioni<\/h2><p>Le informazioni che raccogliamo possono essere utilizzate per:<\/p><ul><li>Personalizza la tua esperienza e soddisfa le tue esigenze individuali<\/li><li>Fornire contenuti pubblicitari personalizzati<\/li><li>Miglioramento del nostro sito web<\/li><li>Migliora il servizio clienti e le tue esigenze di supporto<\/li><li>Contattarti via e-mail<\/li><\/ul><h2>4. Privacy del commercio online<\/h2><p>Siamo gli unici proprietari delle informazioni raccolte su questo sito. Le tue informazioni personali non saranno vendute, scambiate, trasferite o cedute a nessun&#8217;altra societ\u00e0 per nessun motivo, senza il tuo consenso. <\/p><h2>5. Divulgazione a terzi<\/h2><p>Non vendiamo, scambiamo o trasferiamo in altro modo le informazioni di identificazione personale dell&#8217;utente a terzi. Ci\u00f2 non include terze parti fidate che ci assistono nella gestione del nostro sito Web, nella conduzione della nostra attivit\u00e0 o nell&#8217;assistenza all&#8217;utente, a condizione che tali parti accettino di mantenere riservate tali informazioni. <\/p><h2>6. Protezione delle informazioni<\/h2><p>Implementiamo una serie di misure di sicurezza per mantenere al sicuro le tue informazioni personali. Utilizziamo una crittografia all&#8217;avanguardia per proteggere le informazioni sensibili trasmesse online. <\/p><h2>7. Consenso<\/h2><p>Utilizzando il nostro sito, acconsenti alla nostra Informativa sulla privacy.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hurento.ma Informativa sulla privacy 1. Introduzione Benvenuti a Hurento. La presente Informativa sulla privacy spiega come noi di Hurento raccogliamo, utilizziamo, divulghiamo e proteggiamo le informazioni personali degli utenti del nostro sito. 2. Raccolta di informazioni Raccogliamo informazioni quando navighi sul nostro sito, ti registri sul nostro sito e utilizzi i nostri servizi. I tipi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4204","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/pages\/4204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/comments?post=4204"}],"version-history":[{"count":2,"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/pages\/4204\/revisions"}],"predecessor-version":[{"id":4206,"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/pages\/4204\/revisions\/4206"}],"wp:attachment":[{"href":"https:\/\/hurento.ma\/it\/wp-json\/wp\/v2\/media?parent=4204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}